{"id":574,"date":"2021-02-10T20:12:16","date_gmt":"2021-02-10T19:12:16","guid":{"rendered":"http:\/\/www.bandarussi.com\/wordpress\/?p=574"},"modified":"2021-02-10T20:12:18","modified_gmt":"2021-02-10T19:12:18","slug":"sospensione-dell-attivita-della-banda","status":"publish","type":"post","link":"http:\/\/www.bandarussi.com\/wordpress\/sospensione-dell-attivita-della-banda\/","title":{"rendered":"Sospensione dell&#8217; attivit\u00e0 della Banda"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.bandarussi.com\/wordpress\/wp-content\/uploads\/2021\/02\/No_music.svg_.png\"><img loading=\"lazy\" src=\"https:\/\/www.bandarussi.com\/wordpress\/wp-content\/uploads\/2021\/02\/No_music.svg_-1024x1024.png\" alt=\"\" class=\"wp-image-577\" width=\"158\" height=\"158\" srcset=\"http:\/\/www.bandarussi.com\/wordpress\/wp-content\/uploads\/2021\/02\/No_music.svg_.png 1024w, http:\/\/www.bandarussi.com\/wordpress\/wp-content\/uploads\/2021\/02\/No_music.svg_-300x300.png 300w, http:\/\/www.bandarussi.com\/wordpress\/wp-content\/uploads\/2021\/02\/No_music.svg_-150x150.png 150w, http:\/\/www.bandarussi.com\/wordpress\/wp-content\/uploads\/2021\/02\/No_music.svg_-768x768.png 768w, http:\/\/www.bandarussi.com\/wordpress\/wp-content\/uploads\/2021\/02\/No_music.svg_-800x800.png 800w\" sizes=\"(max-width: 158px) 100vw, 158px\" \/><\/a><\/figure><\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p>Si informa il gentile pubblico che, in ottemperanza alle disposizioni contenute nei vari DPCM emanati dal Governo per contenere la pandemia da Covid-19, tutte le attivit\u00e0 della Banda Citt\u00e0 di Russi sono momentaneamente sospese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa il gentile pubblico che, in ottemperanza alle disposizioni contenute nei vari DPCM emanati dal Governo per contenere la pandemia da Covid-19, tutte le attivit\u00e0 della Banda Citt\u00e0 di Russi sono momentaneamente sospese.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/posts\/574"}],"collection":[{"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/comments?post=574"}],"version-history":[{"count":7,"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/posts\/574\/revisions"}],"predecessor-version":[{"id":582,"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/posts\/574\/revisions\/582"}],"wp:attachment":[{"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/media?parent=574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/categories?post=574"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.bandarussi.com\/wordpress\/wp-json\/wp\/v2\/tags?post=574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}